{"id":4211,"date":"2023-12-16T05:48:32","date_gmt":"2023-12-16T04:48:32","guid":{"rendered":"https:\/\/aviation.pero-online.de\/wordpress\/?p=4211"},"modified":"2023-12-28T07:35:34","modified_gmt":"2023-12-28T06:35:34","slug":"frohe-weihnachten","status":"publish","type":"post","link":"https:\/\/aviation.pero-online.de\/wordpress\/frohe-weihnachten\/","title":{"rendered":"Frohe Weihnachten!"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"277\" src=\"https:\/\/aviation.pero-online.de\/wordpress\/wp-content\/uploads\/2023\/12\/weihnachtskerzen-jpg.webp\" alt=\"\" class=\"wp-image-4214\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Ein aufregendes Jahr neigt sich dem Ende zu, und in wenigen Tagen steht Weihnachten vor der T\u00fcr. F\u00fcr mich war es ein Jahr voller Ereignisse, sowohl beruflich als auch privat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seit nunmehr 10 Jahren habe ich mein A320 Homecockpit. Ein besonderes Highlight war die Teilnahme am VATSIM Worldflight in diesem Jahr. Es hat mich besonders gefreut zu sehen, dass Lockheed Martin mit der PREPAR3D Version 5.4 und sp\u00e4ter sogar mit der Version 6 betont hat, dass die Plattform kontinuierlich weiterentwickelt wird. Leider musste ich die 5.4 schnell von meiner Festplatte entfernen, da vermehrt Abst\u00fcrze auftraten, die in der vorherigen Version 5.3 nicht vorhanden waren. Derzeit fehlt mir leider die Zeit, um herauszufinden, warum das der Fall ist. Die Version 6 ist im Moment keine Option f\u00fcr mich, da der Umstieg nach meiner Einsch\u00e4tzung recht zeitaufwendig ist. PREPAR3D wird auch noch eine Weile auf der Platte bleiben, auch wenn der Umstieg auf MSFS m\u00f6glich w\u00e4re. Mein aktuelles Setup erf\u00fcllt meine Bed\u00fcrfnisse, ich habe zahlreiche Payware Addons und m\u00f6chte derzeit nicht die Zeit f\u00fcr einen Umstieg investieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist bedauerlich, dass kaum noch neue Addons oder Updates f\u00fcr PREPAR3D ver\u00f6ffentlicht werden. An dieser Stelle m\u00f6chte ich daher einen gro\u00dfen Dank an FS Dreamteam, HIFI Sim, JeeHell FMGS, und andere aussprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beruflich dreht sich bei mir derzeit alles um das Thema &#8222;K\u00fcnstliche Intelligenz&#8220;. W\u00e4hrend eines angenehmen Fluges mit Micha bin ich \u00fcber diesen Witz gestolpert. Frohe Weihnachten!<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">Nachdem das Flugzeug gestartet ist, erfolgt folgende Durchsage: &#8222;Sehr verehrte Flugg\u00e4ste, sie fliegen mit dem ersten vollautomatischen Passagierflugzeug der Welt. Es befindet sich kein Pilot an Bord, dennoch besteht kein Grund zur Sorge, wir haben alles unter Kontrolle &#8211; unter Kontrolle &#8211; unter Kontrolle &#8211; unter Kontrolle&#8230;&#8220;<\/p>\n<cite>https:\/\/deine-mutter-witze.net\/pilotenwitze.html<\/cite><\/blockquote>\n\n","protected":false},"excerpt":{"rendered":"<p>Ein aufregendes Jahr neigt sich dem Ende zu, und in wenigen Tagen steht Weihnachten vor der T\u00fcr. F\u00fcr mich war es ein Jahr voller Ereignisse, sowohl beruflich als auch privat. Seit nunmehr 10 Jahren habe ich mein A320 Homecockpit. Ein besonderes Highlight war die Teilnahme am VATSIM Worldflight in diesem Jahr. Es hat mich besonders&hellip;&nbsp;<a href=\"https:\/\/aviation.pero-online.de\/wordpress\/frohe-weihnachten\/\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Frohe Weihnachten!<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4211","post","type-post","status-publish","format-standard","hentry","category-sonstiges"],"_links":{"self":[{"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/posts\/4211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/comments?post=4211"}],"version-history":[{"count":0,"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/posts\/4211\/revisions"}],"wp:attachment":[{"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/media?parent=4211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/categories?post=4211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aviation.pero-online.de\/wordpress\/wp-json\/wp\/v2\/tags?post=4211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}